{"id":4232,"date":"2026-07-15T07:40:53","date_gmt":"2026-07-15T05:40:53","guid":{"rendered":"https:\/\/syndikat-eisebunnen.lu\/news\/commentaire-nr-02-2026-2"},"modified":"2026-07-15T07:51:30","modified_gmt":"2026-07-15T05:51:30","slug":"commentaire-nr-03-2026","status":"publish","type":"news","link":"https:\/\/syndikat-eisebunnen.lu\/de\/news\/commentaire-nr-03-2026","title":{"rendered":"Kommentar &#8211; Nr. 03\/2026"},"content":{"rendered":"<p><\/p>\n<h3><strong>Wann d\u2019Gewerkschaften d\u2019St\u00ebmm vum Terrain an der Politik musse sinn<\/strong><\/h3>\n<p><strong>D\u00e9i rezent Tripartite huet nach eng K\u00e9ier gewisen, w\u00e9i wichteg et ass, datt d\u2019Gewerkschaften sech aktiv un de gesellschaftlechen a politeschen Debatte bedeelegen.<\/strong><\/p>\n<p>Net well si eng politesch Partei ersetze w\u00ebllen, m\u00e4 well si d\u2019Aufgab hunn, d\u2019Interesse vun de Salari\u00e9en ze vertrieden an hir St\u00ebmm an d\u00e9i Debatten anzebr\u00e9ngen, wou d\u2019Decisioune fir d\u2019Zukunft vun eisem Land geholl ginn.<\/p>","protected":false},"featured_media":3433,"template":"","news_category":[12],"class_list":["post-4232","news","type-news","status-publish","has-post-thumbnail","hentry","news_category-commentaire"],"acf":[],"_links":{"self":[{"href":"https:\/\/syndikat-eisebunnen.lu\/de\/wp-json\/wp\/v2\/news\/4232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/syndikat-eisebunnen.lu\/de\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/syndikat-eisebunnen.lu\/de\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/syndikat-eisebunnen.lu\/de\/wp-json\/wp\/v2\/media\/3433"}],"wp:attachment":[{"href":"https:\/\/syndikat-eisebunnen.lu\/de\/wp-json\/wp\/v2\/media?parent=4232"}],"wp:term":[{"taxonomy":"news_category","embeddable":true,"href":"https:\/\/syndikat-eisebunnen.lu\/de\/wp-json\/wp\/v2\/news_category?post=4232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}